{"id":5743,"date":"2018-01-11T07:35:54","date_gmt":"2018-01-11T06:35:54","guid":{"rendered":"http:\/\/spvgg-goldkronach.com\/1946\/?p=5743"},"modified":"2018-07-28T13:43:43","modified_gmt":"2018-07-28T11:43:43","slug":"neue-kurse-im-fruehjahr-karate-fitness-faszien","status":"publish","type":"post","link":"https:\/\/spvgg-goldkronach.com\/1946\/2018\/01\/neue-kurse-im-fruehjahr-karate-fitness-faszien\/","title":{"rendered":"Neue Kurse im Fr\u00fchjahr: Karate, Fitness, Faszien"},"content":{"rendered":"<p><strong>Die SpVgg Goldkronach bietet in Zusammenarbeit mit der Volkshochschule (VHS) auch im Fr\u00fchjahr 2018 verschiedene Kurse f\u00fcr Sport und Gesundheit an. Wer fit in das neue Jahr starten m\u00f6chte, sollte sich die Angebote n\u00e4her ansehen!<br \/>\n<\/strong><\/p>\n<hr \/>\n<p><span style=\"color: #c60000;\"><strong>Karate zum Kennenlernen f\u00fcr alle von 10 bis 80 Jahre<\/strong><\/span><\/p>\n<p>Einf\u00fchrungskurs in das traditionelle Shotokan-Karate.<\/p>\n<ul>\n<li>VHS-Kurs: Go 006_4<\/li>\n<li>Beginn: Freitag, 2. M\u00e4rz 2018 (zehn Abende, 17:30\u201318:45 Uhr)<\/li>\n<li>Ort: Alexander-von-Humboldt-Schule, Turnhalle (Hintereingang)<\/li>\n<li>Bitte mitbringen: bequeme Kleidung (barfu\u00df)<\/li>\n<li>Geb\u00fchr: 30 \u20ac<\/li>\n<li>Leitung: Horst Lindner, Reiner Hieckmann<\/li>\n<\/ul>\n<hr \/>\n<p><span style=\"color: #c60000;\"><strong>Fitnesstraining f\u00fcr Frauen jeden Alters mit integriertem Faszientraining<\/strong><\/span><\/p>\n<p>Mach mit \u2013 bleib&#8216; fit! Komm&#8216; zu unserem Workout mit den Schwerpunkten Kreislauftraining, Kr\u00e4ftigung und Faszientraining. Die aktuellen Erkenntnisse der Faszien-Fitness spielen bei unserem Training eine wichtige Rolle. Wir arbeiten mit Hanteln, Overball, Theraband, Stepper und verschiedenen anderen Kleinger\u00e4ten.<\/p>\n<ul>\n<li>VHS-Kurs: Go 005_4<\/li>\n<li>Beginn: Donnerstag, 25. Januar 2018, 18:30\u201319:30 Uhr (10 Abende)<\/li>\n<li>Ort: Alexander-von-Humboldt-Schule, Turnhalle (Hintereingang)<\/li>\n<li>Bitte mitbringen: Gymnastikband, Sportschuhe, Hanteln, Trainingsmatte<\/li>\n<li>Geb\u00fchr: 25 \u20ac<\/li>\n<li>Leitung: Claudia Bauer<\/li>\n<\/ul>\n<hr \/>\n<p><span style=\"color: #c60000;\"><strong>Faszienabrollen<\/strong><\/span><\/p>\n<p>Erlerne das Abrollen mit deiner eigenen Faszienrolle. F\u00fcr Teilnehmerinnen am Kurs Go 005_4 (Fitnesstraining f\u00fcr Frauen) kostenlos enthalten!<\/p>\n<ul>\n<li>VHS-Kurs: Go 007_4<\/li>\n<li>Beginn: Donnerstag, 25. Januar 2018, 19:30 bis 20:00 Uhr (5 Abende)<\/li>\n<li>Ort: Alexander-von-Humboldt-Schule, Turnhalle (Hintereingang)<\/li>\n<li>Bitte mitbringen: Faszienrolle, bequeme Kleidung<\/li>\n<li>Geb\u00fchr: 10 \u20ac<\/li>\n<li>Leitung: Claudia Bauer<\/li>\n<\/ul>\n<hr \/>\n<p><strong>Anmeldung f\u00fcr alle Kurse bei der Stadt Goldkronach:<br \/>\n<\/strong><\/p>\n<ul>\n<li>VHS-Gesch\u00e4ftsstelle im Rathaus Goldkronach<\/li>\n<li>Marktplatz 2, 95497 Goldkronach<\/li>\n<li>Sabine Heyder, Jutta Zapf<\/li>\n<li>Tel. 0 92 73 \/ 984-0<\/li>\n<li>E-mail: sabine.heyder@goldkronach.bayern.de<\/li>\n<\/ul>\n<p>Die Anmeldung ist bis sp\u00e4testens f\u00fcnf Tage vor Kursbeginn m\u00f6glich. Bitte melden Sie sich rechtzeitig an, denn Ihre Anmeldung kann entscheiden, ob ein Kurs stattfindet oder abgesagt werden muss.<\/p>\n<p>Bezahlung: \u00dcberweisung an die VHS Goldkronach, ein \u00dcberweisungsformular erhalten Sie im Rathaus. Barzahlungen k\u00f6nnen wir leider nicht mehr annehmen!<\/p>\n<p>Arbeitslose Mitb\u00fcrger*innen sowie Sozialhilfeempf\u00e4nger*innen erhalten gegen Nachweis eine Erm\u00e4\u00dfigung f\u00fcr alle Kurse aus dem Bildungs- und Gesundheitsbereich. Familienbeitr\u00e4ge auf Anfrage. Bei bestimmten Veranstaltungen und Kursen ist &#8222;schnuppern&#8220; m\u00f6glich, bitte fragen Sie nach!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die SpVgg Goldkronach bietet in Zusammenarbeit mit der Volkshochschule (VHS) auch im Fr\u00fchjahr 2018 verschiedene Kurse f\u00fcr Sport und Gesundheit an. Wer fit in das neue Jahr starten m\u00f6chte, sollte sich die Angebote n\u00e4her ansehen! Karate zum Kennenlernen f\u00fcr alle von 10 bis 80 Jahre Einf\u00fchrungskurs in das traditionelle Shotokan-Karate. VHS-Kurs: Go 006_4 Beginn: Freitag, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5054,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,9],"tags":[754,432,672,755,433],"class_list":["post-5743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karate","category-turnen-fitness","tag-faszien","tag-fitness","tag-karate","tag-kurs","tag-vhs"],"_links":{"self":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts\/5743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/comments?post=5743"}],"version-history":[{"count":3,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts\/5743\/revisions"}],"predecessor-version":[{"id":5746,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts\/5743\/revisions\/5746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/media\/5054"}],"wp:attachment":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/media?parent=5743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/categories?post=5743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/tags?post=5743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}