{"id":2885,"date":"2014-01-25T14:43:07","date_gmt":"2014-01-25T13:43:07","guid":{"rendered":"http:\/\/spvgg-goldkronach.com\/1946\/?p=2885"},"modified":"2014-04-17T14:48:12","modified_gmt":"2014-04-17T12:48:12","slug":"neuer-karate-einfuhrungskurs-mit-der-vhs","status":"publish","type":"post","link":"https:\/\/spvgg-goldkronach.com\/1946\/2014\/01\/neuer-karate-einfuhrungskurs-mit-der-vhs\/","title":{"rendered":"Neuer Karate-Einf\u00fchrungskurs mit der VHS"},"content":{"rendered":"<p>Die SpVgg Goldkronach bietet in Zusammenarbeit mit der Volkshochschule wieder einen Einf\u00fchrungskurs in das traditionelle Shotokan-Karate an \u2013 f\u00fcr alle von zehn bis 80 Jahren. Hier gibt&#8217;s alle Informationen.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Kurs-Nr. GO006_4 Karate zum Kennenlernen f\u00fcr alle von 10 bis 80 Jahre\u00a0 \u00a0<\/strong><\/span><\/p>\n<ul>\n<li>Beginn: Fr., 07.02.2014, Zeit: 17.30-18.45 Uhr<\/li>\n<li>Schule, Hintereingang, Turnhalle<\/li>\n<li>10 Abende<\/li>\n<li>mitzubr.: bequeme Kleidung (barfu\u00df)<\/li>\n<li>Geb\u00fchr: 25,00 EUR<\/li>\n<li>Leitung: Horst Lindner<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\"><strong>Anmeldung f\u00fcr VHS-Kurse<\/strong><\/span><\/p>\n<ul>\n<li>\u00a0\u00a0\u00a0 VHS-Gesch\u00e4ftsstelle im Rathaus Goldkronach<\/li>\n<li>\u00a0\u00a0\u00a0 Marktplatz 2, 95497 Goldkronach<\/li>\n<li>\u00a0\u00a0\u00a0 Sabine Heyder<\/li>\n<li>\u00a0\u00a0\u00a0 Tel. 0 92 73 \/ 984-0, Fax 0 92 73 \/ 984-20<\/li>\n<li>\u00a0\u00a0\u00a0 E-mail: sabine.heyder@goldkronach.bayern.de<\/li>\n<\/ul>\n<p>Anmeldungen f\u00fcr die Kurse sind bis sp\u00e4testens f\u00fcnf Tage vor Kursbeginn m\u00f6glich. Die Bezahlung erfolgt durch \u00dcberweisung an die VHS Goldkronach, Konto-Nr. 570 280 263, BLZ 773 501 10 (Sparkasse Bayreuth) oder bar im Rathaus. Bitte melden Sie sich rechtzeitig an! Arbeitslose Mitb\u00fcrger*innen sowie Sozialhilfeempf\u00e4nger*innen erhalten gegen Nachweis eine Erm\u00e4\u00dfigung f\u00fcr alle Kurse aus dem Bildungs- und Gesundheitsbereich. Familienbeitr\u00e4ge auf Anfrage. Bei bestimmten Veranstaltungen und Kursen ist \u201cschnuppern\u201d m\u00f6glich, bitte fragen Sie nach!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die SpVgg Goldkronach bietet in Zusammenarbeit mit der Volkshochschule wieder einen Einf\u00fchrungskurs in das traditionelle Shotokan-Karate an \u2013 f\u00fcr alle von zehn bis 80 Jahren. Hier gibt&#8217;s alle Informationen. Kurs-Nr. GO006_4 Karate zum Kennenlernen f\u00fcr alle von 10 bis 80 Jahre\u00a0 \u00a0 Beginn: Fr., 07.02.2014, Zeit: 17.30-18.45 Uhr Schule, Hintereingang, Turnhalle 10 Abende mitzubr.: bequeme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1865,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[493,672,433,484],"class_list":["post-2885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karate","tag-einfuhrungskurs","tag-karate","tag-vhs","tag-volkshochschule"],"_links":{"self":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts\/2885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/comments?post=2885"}],"version-history":[{"count":2,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts\/2885\/revisions"}],"predecessor-version":[{"id":2887,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/posts\/2885\/revisions\/2887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/media\/1865"}],"wp:attachment":[{"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/media?parent=2885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/categories?post=2885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spvgg-goldkronach.com\/1946\/wp-json\/wp\/v2\/tags?post=2885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}